{"id":4840,"date":"2021-07-16T16:44:57","date_gmt":"2021-07-16T16:44:57","guid":{"rendered":"https:\/\/cultureartsnetwork.com\/?p=4840"},"modified":"2021-07-16T16:46:37","modified_gmt":"2021-07-16T16:46:37","slug":"association-minarets-ecologiques-pour-le-developpement-et-climat-maroc","status":"publish","type":"post","link":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/","title":{"rendered":"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"4840\" class=\"elementor elementor-4840\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4da602 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4da602\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6b63a7\" data-id=\"e6b63a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4fc7fa elementor-widget elementor-widget-text-editor\" data-id=\"d4fc7fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table width=\"100%\"><tbody><tr><td><p><strong><br \/>\u0623\u0633\u0645 \u0627\u0644\u062c\u0645\u0639\u064a\u0629 \u0623\u0648 \u0627\u0644\u0641\u0631\u062f<\/strong><\/p><\/td><\/tr><tr><td><p>Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><table width=\"100%\"><tbody><tr><td><p><strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<\/strong><\/p><\/td><\/tr><tr><td><p><a href=\"mailto:benramelmostafa@gmail.com\">benramelmostafa@gmail.com<\/a><\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><p>\u00a0<\/p><table width=\"100%\"><tbody><tr><td><p><strong>\u0627\u0644\u0639\u0646\u0648\u0627\u0646<\/strong><\/p><\/td><\/tr><tr><td><p>Rue 182 N\u00b04441 Hay ELOUAHDA 14030 KENITRA<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><table width=\"100%\"><tbody><tr><td><p><strong>\u0627\u0644\u0628\u0644\u062f<\/strong><\/p><\/td><\/tr><tr><td><p>MAROC<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><p>\u00a0<\/p><table width=\"100%\"><tbody><tr><td><p><strong>Website URL<\/strong><\/p><\/td><\/tr><tr><td><p><a href=\"https:\/\/minaretsecologiques.ahlamontada.com\/\">https:\/\/minaretsecologiques.ahlamontada.com\/<\/a><\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><table width=\"100%\"><tbody><tr><td><p><strong>\u0627\u0644\u0623\u0647\u062f\u0627\u0641 \u0648\u0627\u0644\u0645\u0647\u0627\u0645<\/strong><\/p><\/td><\/tr><tr><td><p>Nous sommes une association de d\u00e9veloppement marocaine qui s&#8217;int\u00e9resse \u00e0 d\u00e9velopper l\u2019\u00eatre humain, l&#8217;environnement et le climat par l&#8217;int\u00e9gration des droits humains et des approches de d\u00e9veloppement pour atteindre un d\u00e9veloppement global avec une dimension locale, r\u00e9gionale, nationale, africaine et internationale au service de d\u00e9veloppement, d&#8217;environnement et de climat.<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><table width=\"100%\"><tbody><tr><td><p><strong>\u0627\u0644\u0623\u0646\u0634\u0637\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/strong><\/p><\/td><\/tr><tr><td><p>1) \u00e9laboration et mise en \u0153uvre de projets multidisciplinaires par int\u00e9gration les approches de d\u00e9veloppement, d&#8217;environnement et de climat ;<br \/>2) Organisation des formations, des tables rondes et des conf\u00e9rences et conf\u00e9rences locales, r\u00e9gionales, nationales, r\u00e9gionales, africaines et internationales ;<br \/>3) Participation \u00e0 des formations, des tables rondes et des forums locaux, r\u00e9gionaux, nationaux, r\u00e9gionaux, africains et internationaux ;<br \/>4) Pr\u00e9paration et mettre en \u0153uvre des projets de d\u00e9veloppement et de solidarit\u00e9 qui g\u00e9n\u00e8rent des opportunit\u00e9s \u00e9conomiques, individuelles et collectives, pour les jeunes et les femmes dans les zones urbaines et rurales surtout les plus vuln\u00e9rables ;<br \/>5) Contribution \u00e0 soutenir l&#8217;\u00e9cole et l&#8217;apprentissage par le biais de programmes de soutien scolaire, d&#8217;\u00e9ducation parall\u00e8le, d&#8217;\u00e9ducation non formelle, d&#8217;alphab\u00e9tisation et d&#8217;universit\u00e9s populaires et publiques ;<br \/>6) Organisation des campagnes de sensibilisation, des activit\u00e9s sociales et solidaires, des convois m\u00e9dicaux, environnementaux et climatiques ;<br \/>7) Diffusion et soutien de la tol\u00e9rance, de la paix et de la diversit\u00e9 culturelle \u00e0 travers les ateliers de langues globales et les forums de coexistence, de tol\u00e9rance et de dialogue de civilisations ;<br \/>8) Soutenir la diplomatie parall\u00e8le au niveau r\u00e9gional, africain et international pour servir les constantes nationales et le d\u00e9veloppement et la prosp\u00e9rit\u00e9 de la patrie ;<br \/>9) Organisation des concerts artistiques et des soir\u00e9es r\u00e9cr\u00e9atives \u00e0 travers des mat\u00e9riaux litt\u00e9raires, artistiques, comiques, patrimoniaux et culturels ;<br \/>10) Organisation et participation \u00e0 des expositions \u00e0 l&#8217;\u00e9chelle nationale, r\u00e9gionale, africaine et internationale ;<br \/>11) Organisation des voyages, d\u2019excursions, des aventures et des \u00e9tudes de d\u00e9veloppement, environnementales et climatologiques en accord avec la perspective de d\u00e9veloppement de l\u2019\u00e9cotourisme ;<br \/>12) Organisation des ateliers participatifs pour les jeunes, des camps d&#8217;\u00e9t\u00e9, des comp\u00e9titions culturelles, artistiques et sportives et des festivals qui favorisent la tol\u00e9rance et le dialogue interculturel ;<br \/>13) Cr\u00e9ation l&#8217;Observatoire pour le D\u00e9veloppement, l&#8217;Environnement et le Changement Climatique, affili\u00e9 \u00e0 la Soci\u00e9t\u00e9 pour mener des \u00e9tudes socio-\u00e9conomiques, d\u00e9veloppementales, environnementales et climatiques.<br \/>14) Cr\u00e9ation l\u2019Observatoire des jeunes et des femmes et d\u00e9velopper des opportunit\u00e9s individuelles et collectives pour soutenir et r\u00e9aliser le d\u00e9veloppement global de la jeunesse dans le pays ;<br \/>15) Cr\u00e9ation de l&#8217;Observatoire de l&#8217;\u00e9ducation environnementale et du d\u00e9veloppement pour le d\u00e9veloppement des enfants et des jeunes sur les valeurs de la protection de l&#8217;environnement et la consolidation de l&#8217;esprit de citoyennet\u00e9, de tol\u00e9rance et de dialogue des cultures.<br \/>16) Cr\u00e9ation des clubs sp\u00e9cialis\u00e9s en fonction des espaces sociaux, d\u00e9veloppementaux, environnementaux et climatiques \u00e0 approuver par l&#8217;assembl\u00e9e g\u00e9n\u00e9rale ordinaire ou extraordinaire ou la r\u00e9union du Bureau de l&#8217;Assembl\u00e9e.<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><p>\u00a0<\/p><table width=\"100%\"><tbody><tr><td><p><strong>\u0623\u064a \u0623\u0636\u0627\u0641\u0629 \u061f<\/strong><\/p><\/td><\/tr><tr><td><p>\u2022<br \/>Actions de l\u2019Education en environnement pour les enfants, jeunes et universitaires avec nos organismes associatives partenaire dans le Maroc ;<br \/>\u2022 Actions de sensibilisation pour les citoyens et les acteurs de la soci\u00e9t\u00e9 civile avec nos organismes associatives partenaire dans le Maroc ;<br \/>\u2022 Projet d\u2019int\u00e9gration la proche environnementale dans les politiques publiques de la chose territoriale avec nos organismes associatives partenaire dans le Maroc ;<br \/>\u2022 Plaidoyer pour lutter contre la pollution des d\u00e9chets m\u00e9nagers solides avec nos organismes associatives partenaire dans le Maroc ;<br \/>Projet en cours :<br \/>Projet1 : Vague des activit\u00e9s de la sensibilisation et la vulgarisation les th\u00e8mes des journ\u00e9es mondiales en sujets de d\u00e9veloppement, d\u2019environnement, et de climat \u00ab Vulgar\u2019Environnement#Day \u00bb :<br \/>\u2022 Par la diffusion la c\u00e9l\u00e9bration de la journ\u00e9e, son th\u00e8me, les outils p\u00e9dagogiques utilis\u00e9s, les articles publi\u00e9s selon les th\u00e8mes ;<br \/>\u2022 Par organisation des ateliers de formations et de sensibilisation pour les enfants, les jeunes et les adultes ;<br \/>\u2022 Par diffusion ses activit\u00e9s dans les m\u00e9dias et les groupes sociaux de notre organisme, nos partenaires et nos suivis.<br \/>Projet 2 :Campagne sensibilisation pour combattre la pollution des plastiques : \u00ab Act\u2019#Fin de la pollution de plastique en 2022 \u00bb :<br \/>\u2022 Par organisation des ateliers de formations et de sensibilisation pour les enfants, les jeunes et les adultes sur le th\u00e8me du plastique ;<br \/>Projet 3 : Une plateforme d\u2019\u00e9ducation \u00e0 l\u2019environnement et de climat pour \u00e9duquer les enfants, les adolescents, les jeunes et les acteurs de la soci\u00e9t\u00e9 civile intitul\u00e9 : \u00ab Universit\u00e9 ouvert \u00e9co-start des jeunes \u00bb :<br \/>\u2022 Organisation des formations actions sp\u00e9cifiques dans le domaine de pr\u00e9servation de l\u2019environnement et l\u2019am\u00e9lioration de ses composantes naturelles dans les \u00e9tablissements scolaires, universitaires, espaces des jeunes et publics ;<br \/>\u2022 Organisation des formations de plaidoyer contre les politiques publiques et les actions priv\u00e9es qui entrainent la d\u00e9gradation de l\u2019environnement.<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Name of the organization or artist Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4840","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc - ACAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc - ACAN\" \/>\n<meta property=\"og:description\" content=\"Name of the organization or artist Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/\" \/>\n<meta property=\"og:site_name\" content=\"ACAN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acannetwork\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-16T16:44:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-16T16:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mhamed AKKAWI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acannetwork\" \/>\n<meta name=\"twitter:site\" content=\"@acannetwork\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mhamed AKKAWI\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/\"},\"author\":{\"name\":\"Mhamed AKKAWI\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#\\\/schema\\\/person\\\/3a2d4a89bbfeb9de8df230c1d41c8da8\"},\"headline\":\"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc\",\"datePublished\":\"2021-07-16T16:44:57+00:00\",\"dateModified\":\"2021-07-16T16:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/\"},\"wordCount\":880,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/\",\"name\":\"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc - ACAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#website\"},\"datePublished\":\"2021-07-16T16:44:57+00:00\",\"dateModified\":\"2021-07-16T16:46:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cultureartsnetwork.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/\",\"name\":\"Arab Culture and Arts Network\",\"description\":\"Arab Culture and Arts Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#organization\"},\"alternateName\":\"ACAN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#organization\",\"name\":\"ARAB CULTURE AND ARTS NETWORK\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/jpg-LR.jpeg\",\"contentUrl\":\"https:\\\/\\\/cultureartsnetwork.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/jpg-LR.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"ARAB CULTURE AND ARTS NETWORK\"},\"image\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acannetwork\",\"https:\\\/\\\/x.com\\\/acannetwork\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#\\\/schema\\\/person\\\/3a2d4a89bbfeb9de8df230c1d41c8da8\",\"name\":\"Mhamed AKKAWI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85df7f7b3dee0f0a7cab9a744447616b75dcd4ad823dabc8ca2b51371b93035?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85df7f7b3dee0f0a7cab9a744447616b75dcd4ad823dabc8ca2b51371b93035?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85df7f7b3dee0f0a7cab9a744447616b75dcd4ad823dabc8ca2b51371b93035?s=96&d=mm&r=g\",\"caption\":\"Mhamed AKKAWI\"},\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/author\\\/mhamed-akkawi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc - ACAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/","og_locale":"ar_AR","og_type":"article","og_title":"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc - ACAN","og_description":"Name of the organization or artist Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc [&hellip;]","og_url":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/","og_site_name":"ACAN","article_publisher":"https:\/\/www.facebook.com\/acannetwork","article_published_time":"2021-07-16T16:44:57+00:00","article_modified_time":"2021-07-16T16:46:37+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg","type":"image\/jpeg"}],"author":"Mhamed AKKAWI","twitter_card":"summary_large_image","twitter_creator":"@acannetwork","twitter_site":"@acannetwork","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"Mhamed AKKAWI","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"4 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/#article","isPartOf":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/"},"author":{"name":"Mhamed AKKAWI","@id":"https:\/\/cultureartsnetwork.com\/ar\/#\/schema\/person\/3a2d4a89bbfeb9de8df230c1d41c8da8"},"headline":"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc","datePublished":"2021-07-16T16:44:57+00:00","dateModified":"2021-07-16T16:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/"},"wordCount":880,"commentCount":0,"publisher":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"ar","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/","url":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/","name":"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc - ACAN","isPartOf":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/#website"},"datePublished":"2021-07-16T16:44:57+00:00","dateModified":"2021-07-16T16:46:37+00:00","breadcrumb":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cultureartsnetwork.com\/ar\/association-minarets-ecologiques-pour-le-developpement-et-climat-maroc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cultureartsnetwork.com\/"},{"@type":"ListItem","position":2,"name":"Association Minarets Ecologiques pour le D\u00e9veloppement et Climat Maroc"}]},{"@type":"WebSite","@id":"https:\/\/cultureartsnetwork.com\/ar\/#website","url":"https:\/\/cultureartsnetwork.com\/ar\/","name":"\u0634\u0628\u0643\u0629 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0648\u0627\u0644\u0641\u0646\u0648\u0646 \u0627\u0644\u0639\u0631\u0628\u064a\u0629","description":"\u0634\u0628\u0643\u0629 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0648\u0627\u0644\u0641\u0646\u0648\u0646 \u0627\u0644\u0639\u0631\u0628\u064a\u0629","publisher":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/#organization"},"alternateName":"ACAN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cultureartsnetwork.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/cultureartsnetwork.com\/ar\/#organization","name":"\u0634\u0628\u0643\u0629 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0648\u0627\u0644\u0641\u0646\u0648\u0646 \u0627\u0644\u0639\u0631\u0628\u064a\u0629","url":"https:\/\/cultureartsnetwork.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/cultureartsnetwork.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg","contentUrl":"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg","width":1280,"height":1280,"caption":"ARAB CULTURE AND ARTS NETWORK"},"image":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acannetwork","https:\/\/x.com\/acannetwork"]},{"@type":"Person","@id":"https:\/\/cultureartsnetwork.com\/ar\/#\/schema\/person\/3a2d4a89bbfeb9de8df230c1d41c8da8","name":"Mhamed AKKAWI","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/a85df7f7b3dee0f0a7cab9a744447616b75dcd4ad823dabc8ca2b51371b93035?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85df7f7b3dee0f0a7cab9a744447616b75dcd4ad823dabc8ca2b51371b93035?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85df7f7b3dee0f0a7cab9a744447616b75dcd4ad823dabc8ca2b51371b93035?s=96&d=mm&r=g","caption":"Mhamed AKKAWI"},"url":"https:\/\/cultureartsnetwork.com\/ar\/author\/mhamed-akkawi\/"}]}},"_links":{"self":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/posts\/4840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/comments?post=4840"}],"version-history":[{"count":4,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/posts\/4840\/revisions"}],"predecessor-version":[{"id":4844,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/posts\/4840\/revisions\/4844"}],"wp:attachment":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/media?parent=4840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/categories?post=4840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/tags?post=4840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}