{"id":8170,"date":"2021-08-20T19:14:35","date_gmt":"2021-08-20T19:14:35","guid":{"rendered":"https:\/\/cultureartsnetwork.com\/?page_id=8170"},"modified":"2021-08-28T09:12:43","modified_gmt":"2021-08-28T09:12:43","slug":"oman-cinemas","status":"publish","type":"page","link":"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/","title":{"rendered":"Oman &#8211; Cinemas"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8170\" class=\"elementor elementor-8170\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6065f71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6065f71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-738e0b3\" data-id=\"738e0b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d50c2f8 elementor-widget elementor-widget-toggle\" data-id=\"d50c2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2231\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2231\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Muscat\u00a0Grand Mall<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2231\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/mgm?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/mgm?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2232\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2232\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Stars Cinema<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2232\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2232\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2233\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2233\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Azaiba<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2233\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2233\"><p><a href=\"https:\/\/oman.voxcinemas.com\/showtimes?c=azaiba?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/showtimes?c=azaiba?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2234\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2234\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Ruwi<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2234\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2234\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/ruwi?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/ruwi?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2235\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2235\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2235\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2235\"><p><a href=\"https:\/\/oman.voxcinemas.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2236\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2236\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Al Bahja Cinema<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2236\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2236\"><p><a href=\"http:\/\/albahjacinemaoman.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/albahjacinemaoman.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2237\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2237\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas\u00a0Panorama Mall<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2237\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2237\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/panorama?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/panorama?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2238\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2238\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Lunar Cinemas\u00a0<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2238\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2238\"><p><a href=\"http:\/\/lunarcinemas.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/lunarcinemas.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2239\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2239\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Novo Cinemas, Mall of\u00a0Muscat<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2239\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2239\"><p><a href=\"https:\/\/om.novocinemas.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/om.novocinemas.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22310\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-22310\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Shati<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22310\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-22310\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/shatti?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/shatti?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22311\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-22311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">4DX<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-22311\"><p><a href=\"https:\/\/oman.voxcinemas.com\/ways-to-watch\/4dx\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/ways-to-watch\/4dx<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22312\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-22312\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinema Nizwa\u00a0Grand Mall<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-22312\"><p><a href=\"https:\/\/oman.voxcinemas.com\/movies\/whatson\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/movies\/whatson<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22313\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-22313\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Cinepolis Avenues\u00a0Mall Muscat<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-22313\"><p><a href=\"https:\/\/oman.cinepolisgulf.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.cinepolisgulf.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22314\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-22314\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Suhar<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22314\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-22314\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/shatti?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/shatti?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22315\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-22315\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">City Cinemas Ruwi<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22315\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-22315\"><p><a href=\"https:\/\/oman.cinepolisgulf.com\/browsing\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.cinepolisgulf.com\/browsing<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22316\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-22316\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Cinepolis<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22316\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-22316\"><p><a href=\"http:\/\/cinepolis.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/cinepolis.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22317\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-22317\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Oman Drive In\u00a0Cinema<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22317\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-22317\"><p><a href=\"http:\/\/www.omandriveincinema.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.omandriveincinema.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22318\" class=\"elementor-tab-title\" data-tab=\"18\" role=\"button\" aria-controls=\"elementor-tab-content-22318\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Sur<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22318\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"18\" role=\"region\" aria-labelledby=\"elementor-tab-title-22318\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/sur?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/sur?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22319\" class=\"elementor-tab-title\" data-tab=\"19\" role=\"button\" aria-controls=\"elementor-tab-content-22319\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Buraimi<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22319\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"19\" role=\"region\" aria-labelledby=\"elementor-tab-title-22319\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/buraimi?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/buraimi?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22320\" class=\"elementor-tab-title\" data-tab=\"20\" role=\"button\" aria-controls=\"elementor-tab-content-22320\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Home Cinema<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22320\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"20\" role=\"region\" aria-labelledby=\"elementor-tab-title-22320\"><p><a href=\"http:\/\/www.h-cinema.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.h-cinema.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22321\" class=\"elementor-tab-title\" data-tab=\"21\" role=\"button\" aria-controls=\"elementor-tab-content-22321\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">VOX Cinemas Qurum\u00a0City Centre<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"21\" role=\"region\" aria-labelledby=\"elementor-tab-title-22321\"><p><a href=\"https:\/\/oman.voxcinemas.com\/cinemas\/city-centre-qurum?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic\" target=\"_blank\" rel=\"noopener\">https:\/\/oman.voxcinemas.com\/cinemas\/city-centre-qurum?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22322\" class=\"elementor-tab-title\" data-tab=\"22\" role=\"button\" aria-controls=\"elementor-tab-content-22322\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Cin\u00e9polis Cinemas - Oman Avenues Mall<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"22\" role=\"region\" aria-labelledby=\"elementor-tab-title-22322\"><p><a href=\"http:\/\/www.cinepolisgulf.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.cinepolisgulf.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22323\" class=\"elementor-tab-title\" data-tab=\"23\" role=\"button\" aria-controls=\"elementor-tab-content-22323\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">City Cinema Ruwi<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22323\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"23\" role=\"region\" aria-labelledby=\"elementor-tab-title-22323\"><p><a href=\"http:\/\/www.citycinemaoman.net\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.citycinemaoman.net\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22324\" class=\"elementor-tab-title\" data-tab=\"24\" role=\"button\" aria-controls=\"elementor-tab-content-22324\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Star Cinemas Ibri<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22324\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"24\" role=\"region\" aria-labelledby=\"elementor-tab-title-22324\"><p><a href=\"http:\/\/www.starcinemas.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.starcinemas.com\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22325\" class=\"elementor-tab-title\" data-tab=\"25\" role=\"button\" aria-controls=\"elementor-tab-content-22325\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-left\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">City Cinema<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22325\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"25\" role=\"region\" aria-labelledby=\"elementor-tab-title-22325\"><p><a href=\"https:\/\/citycinemaoman.net\/\" target=\"_blank\" rel=\"noopener\">https:\/\/citycinemaoman.net\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>VOX Cinemas Muscat\u00a0Grand Mall https:\/\/oman.voxcinemas.com\/cinemas\/mgm?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic Stars Cinema VOX Cinemas Azaiba https:\/\/oman.voxcinemas.com\/showtimes?c=azaiba?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic VOX Cinemas Ruwi https:\/\/oman.voxcinemas.com\/cinemas\/ruwi?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwide.php","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-8170","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oman - Cinemas - ACAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oman - Cinemas - ACAN\" \/>\n<meta property=\"og:description\" content=\"VOX Cinemas Muscat\u00a0Grand Mall https:\/\/oman.voxcinemas.com\/cinemas\/mgm?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic Stars Cinema VOX Cinemas Azaiba https:\/\/oman.voxcinemas.com\/showtimes?c=azaiba?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic VOX Cinemas Ruwi https:\/\/oman.voxcinemas.com\/cinemas\/ruwi?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/\" \/>\n<meta property=\"og:site_name\" content=\"ACAN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acannetwork\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-28T09:12:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@acannetwork\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f\u0642\u064a\u0642\u062a\u0627\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/oman-cinemas\\\/\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/oman-cinemas\\\/\",\"name\":\"Oman - Cinemas - ACAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#website\"},\"datePublished\":\"2021-08-20T19:14:35+00:00\",\"dateModified\":\"2021-08-28T09:12:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/oman-cinemas\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/oman-cinemas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/oman-cinemas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cultureartsnetwork.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oman &#8211; Cinemas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/\",\"name\":\"Arab Culture and Arts Network\",\"description\":\"Arab Culture and Arts Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#organization\"},\"alternateName\":\"ACAN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#organization\",\"name\":\"ARAB CULTURE AND ARTS NETWORK\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cultureartsnetwork.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/jpg-LR.jpeg\",\"contentUrl\":\"https:\\\/\\\/cultureartsnetwork.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/jpg-LR.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"ARAB CULTURE AND ARTS NETWORK\"},\"image\":{\"@id\":\"https:\\\/\\\/cultureartsnetwork.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acannetwork\",\"https:\\\/\\\/x.com\\\/acannetwork\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oman - Cinemas - ACAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/","og_locale":"ar_AR","og_type":"article","og_title":"Oman - Cinemas - ACAN","og_description":"VOX Cinemas Muscat\u00a0Grand Mall https:\/\/oman.voxcinemas.com\/cinemas\/mgm?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic Stars Cinema VOX Cinemas Azaiba https:\/\/oman.voxcinemas.com\/showtimes?c=azaiba?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic VOX Cinemas Ruwi https:\/\/oman.voxcinemas.com\/cinemas\/ruwi?utm_source=google&amp;utm_campaign=local_search&amp;utm_medium=organic [&hellip;]","og_url":"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/","og_site_name":"ACAN","article_publisher":"https:\/\/www.facebook.com\/acannetwork","article_modified_time":"2021-08-28T09:12:43+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@acannetwork","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u062a\u0627\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/","url":"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/","name":"Oman - Cinemas - ACAN","isPartOf":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/#website"},"datePublished":"2021-08-20T19:14:35+00:00","dateModified":"2021-08-28T09:12:43+00:00","breadcrumb":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cultureartsnetwork.com\/ar\/oman-cinemas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cultureartsnetwork.com\/"},{"@type":"ListItem","position":2,"name":"Oman &#8211; Cinemas"}]},{"@type":"WebSite","@id":"https:\/\/cultureartsnetwork.com\/ar\/#website","url":"https:\/\/cultureartsnetwork.com\/ar\/","name":"\u0634\u0628\u0643\u0629 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0648\u0627\u0644\u0641\u0646\u0648\u0646 \u0627\u0644\u0639\u0631\u0628\u064a\u0629","description":"\u0634\u0628\u0643\u0629 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0648\u0627\u0644\u0641\u0646\u0648\u0646 \u0627\u0644\u0639\u0631\u0628\u064a\u0629","publisher":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/#organization"},"alternateName":"ACAN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cultureartsnetwork.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/cultureartsnetwork.com\/ar\/#organization","name":"\u0634\u0628\u0643\u0629 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0648\u0627\u0644\u0641\u0646\u0648\u0646 \u0627\u0644\u0639\u0631\u0628\u064a\u0629","url":"https:\/\/cultureartsnetwork.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/cultureartsnetwork.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg","contentUrl":"https:\/\/cultureartsnetwork.com\/wp-content\/uploads\/2024\/02\/jpg-LR.jpeg","width":1280,"height":1280,"caption":"ARAB CULTURE AND ARTS NETWORK"},"image":{"@id":"https:\/\/cultureartsnetwork.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acannetwork","https:\/\/x.com\/acannetwork"]}]}},"_links":{"self":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/pages\/8170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/comments?post=8170"}],"version-history":[{"count":76,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/pages\/8170\/revisions"}],"predecessor-version":[{"id":10333,"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/pages\/8170\/revisions\/10333"}],"wp:attachment":[{"href":"https:\/\/cultureartsnetwork.com\/ar\/wp-json\/wp\/v2\/media?parent=8170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}